{"id":1378,"date":"2013-01-29T17:17:40","date_gmt":"2013-01-29T16:17:40","guid":{"rendered":"http:\/\/www.telegim.tv\/particulares\/?p=1378"},"modified":"2022-05-31T10:46:39","modified_gmt":"2022-05-31T08:46:39","slug":"pilates-intermedio-sesion-completa-sandra","status":"publish","type":"post","link":"https:\/\/www.telegim.tv\/particulares\/pilates-intermedio-sesion-completa-sandra\/","title":{"rendered":"Video Clase PILATES INTERMEDIO SESI\u00d3N COMPLETA"},"content":{"rendered":"<p>Tiempo 50\u201910\u2033 (46-60')<br \/>\nDificultad : 3<br \/>\nT\u00edtulo Pilates intermedio sesi\u00f3n completa<br \/>\nDisciplina Pilates<br \/>\nProfesor Sandra de Haro<br \/>\nObjetivos abdominales, piernas, estiramientos<\/p>\n<p>Descripci\u00f3n Clase de pilates intermedio, siguiendo la secuencia del pilates cl\u00e1sico. Para la pr\u00e1ctica de esta sesi\u00f3n necesitaremos la colchoneta.<br \/>\nComenzaremos con una relajaci\u00f3n de la musculatura a trav\u00e9s de la respiraci\u00f3n y una postura c\u00f3moda...<\/p>\n<p>El pilates es un m\u00e9todo de ejercicio y movimiento f\u00edsico. Su objetivo es fortalecer y equilibrar cuerpo y mente. A trav\u00e9s de la pr\u00e1ctica sistem\u00e1tica de ejercicios de pilates, el pilates ha demostrado tener un valor incalculable. No solo resulta beneficioso para personas que quieran tener y\/o mantener una buena condici\u00f3n f\u00edsica y mental. Tambi\u00e9n supone un importante complemento a la pr\u00e1ctica deportiva y a la rehabilitaci\u00f3n f\u00edsica. Joseph Pilates fue el creador de este innovador sistema de ejercicios de cuerpo y mente. A trav\u00e9s de la pr\u00e1ctica de pilates, podr\u00e1s transformar la manera en la que sientes tu cuerpo, as\u00ed como la forma de actuar.<\/p>\n<div class=\"rtng-rating-total\" data-id=\"1378\"><span class=\"rtng-text rtng-title\">Puntuaci\u00f3n media<\/span><div class=\"rtng-star-rating rtng-no-js \" data-rating=\"0\"><div class=\"rtng-star\" data-rating=\"1\">\n\t\t\t\t\t<span class=\"dashicons dashicons-star-empty\"><\/span>\n\t\t\t\t<\/div><div class=\"rtng-star\" data-rating=\"2\">\n\t\t\t\t\t<span class=\"dashicons dashicons-star-empty\"><\/span>\n\t\t\t\t<\/div><div class=\"rtng-star\" data-rating=\"3\">\n\t\t\t\t\t<span class=\"dashicons dashicons-star-empty\"><\/span>\n\t\t\t\t<\/div><div class=\"rtng-star\" data-rating=\"4\">\n\t\t\t\t\t<span class=\"dashicons dashicons-star-empty\"><\/span>\n\t\t\t\t<\/div><div class=\"rtng-star\" data-rating=\"5\">\n\t\t\t\t\t<span class=\"dashicons dashicons-star-empty\"><\/span>\n\t\t\t\t<\/div><\/div><span class=\"rtng-text rtng-total\">Sistema Operativo<\/span><\/div> <div class=\"rtng-need-login\">Debe <a href=\"https:\/\/www.telegim.tv\/particulares\/wp-login.php\">iniciar sesi\u00f3n<\/a> enviar una opini\u00f3n.<\/div>","protected":false},"excerpt":{"rendered":"<p>Tiempo 50\u201910\u2033 (46-60&#8242;) Dificultad : 3 T\u00edtulo Pilates intermedio sesi\u00f3n completa Disciplina Pilates Profesor Sandra de Haro Objetivos abdominales, piernas, estiramientos Descripci\u00f3n Clase de pilates intermedio, siguiendo la secuencia del pilates cl\u00e1sico. Para la pr\u00e1ctica de esta sesi\u00f3n necesitaremos la colchoneta. Comenzaremos con una relajaci\u00f3n de la musculatura a trav\u00e9s de la respiraci\u00f3n y una [&hellip;]<\/p>\n","protected":false},"author":24681,"featured_media":1380,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,8],"tags":[239,253,270],"class_list":["post-1378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pilates","category-yoga","tag-estirar","tag-intermedio","tag-clases-de-pilates"],"_links":{"self":[{"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/posts\/1378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/users\/24681"}],"replies":[{"embeddable":true,"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/comments?post=1378"}],"version-history":[{"count":0,"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/posts\/1378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/media\/1380"}],"wp:attachment":[{"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/media?parent=1378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/categories?post=1378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.telegim.tv\/particulares\/wp-json\/wp\/v2\/tags?post=1378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}